{"id":45614,"date":"2024-05-28T06:03:09","date_gmt":"2024-05-28T06:03:09","guid":{"rendered":"https:\/\/chezaspin.com\/blog\/index.php\/2024\/05\/28\/in-courts-george-thuo-murder-convicts-to-mitigate-today\/"},"modified":"2024-05-28T06:03:09","modified_gmt":"2024-05-28T06:03:09","slug":"in-courts-george-thuo-murder-convicts-to-mitigate-today","status":"publish","type":"post","link":"https:\/\/chezaspin.com\/blog\/in-courts-george-thuo-murder-convicts-to-mitigate-today\/","title":{"rendered":"In courts: George Thuo murder convicts to mitigate today"},"content":{"rendered":"<p>Wheels of Justice: Court stories lined up for today.<\/p>","protected":false},"excerpt":{"rendered":"<p>Wheels of Justice: Court stories lined up for today.<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-45614","post","type-post","status-publish","format-standard","hentry","category-uncategorized","entry"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/chezaspin.com\/blog\/wp-json\/wp\/v2\/posts\/45614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chezaspin.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chezaspin.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/chezaspin.com\/blog\/wp-json\/wp\/v2\/comments?post=45614"}],"version-history":[{"count":0,"href":"https:\/\/chezaspin.com\/blog\/wp-json\/wp\/v2\/posts\/45614\/revisions"}],"wp:attachment":[{"href":"https:\/\/chezaspin.com\/blog\/wp-json\/wp\/v2\/media?parent=45614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chezaspin.com\/blog\/wp-json\/wp\/v2\/categories?post=45614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chezaspin.com\/blog\/wp-json\/wp\/v2\/tags?post=45614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}